{"id":4544,"date":"2022-03-02T07:01:01","date_gmt":"2022-03-02T07:01:01","guid":{"rendered":"https:\/\/vwo.com\/glossary\/click-through-rate\/"},"modified":"2025-12-02T15:37:08","modified_gmt":"2025-12-02T15:37:08","slug":"taxa-de-cliques","status":"publish","type":"post","link":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/","title":{"rendered":"Taxa de cliques (CTR)"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong><strong>O que \u00e9 taxa de cliques (CTR)?<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A taxa de cliques (CTR) \u00e9 uma m\u00e9trica de marketing digital usada para medir o desempenho de um an\u00fancio. Ela indica o n\u00famero de cliques recebidos na campanha em rela\u00e7\u00e3o ao n\u00famero de visualiza\u00e7\u00f5es (impress\u00f5es). Geralmente, a taxa \u00e9 exibida como porcentagem.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Embora a CTR possa ser medida na maioria dos canais de marketing digital, ela costuma ser usada para monitorar campanhas de PPC, SEO, an\u00fancios pagos em redes sociais e e-mail marketing. \u00c9 a op\u00e7\u00e3o ideal para essas campanhas, pois elas compartilham o objetivo comum de direcionar os usu\u00e1rios para p\u00e1ginas espec\u00edficas. Exemplos comuns em que a CTR \u00e9 medida s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Links ou CTAs em landing pages<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Uma taxa de cliques mais alta em links ou CTAs em uma landing page confirma que seu conte\u00fado e design s\u00e3o relevantes o suficiente para que os visitantes realizem as a\u00e7\u00f5es necess\u00e1rias, como clicar em outras p\u00e1ginas, preencher um formul\u00e1rio ou se registrar.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Links de e-mail<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">CTR representa a porcentagem de destinat\u00e1rios que clicaram no link de um e-mail em rela\u00e7\u00e3o ao n\u00famero total de destinat\u00e1rios que receberam esse e-mail. Uma CTR alta indica que o conte\u00fado do e-mail e os CTAs foram convincentes o suficiente para levar os destinat\u00e1rios a tomarem uma a\u00e7\u00e3o.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>An\u00fancios PPC<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">CTR \u00e9 uma m\u00e9trica amplamente usada no Google Ads e em outras plataformas similares para avaliar a efic\u00e1cia dos an\u00fancios de pesquisa. Uma CTR elevada indica que o p\u00fablico considera seus an\u00fancios relevantes e \u00fateis para responder \u00e0s suas consultas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>An\u00fancios pagos em redes sociais<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">No contexto de an\u00fancios pagos em redes sociais, a CTR indica o n\u00edvel de sucesso de uma campanha publicit\u00e1ria em termos de gera\u00e7\u00e3o de engajamento e tr\u00e1fego para um site ou landing page.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Elementos do site, como bot\u00f5es, imagens e mais<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Ao monitorar a CTR nesses elementos, os propriet\u00e1rios de sites conseguem identificar \u00e1reas para melhorias, o que inclui <a href=\"https:\/\/vwo.com\/br\/testing\/\">otimizar<\/a> o posicionamento, o tamanho, a cor ou o texto de bot\u00f5es, links ou imagens de CTA para aumentar o engajamento e as <a href=\"https:\/\/vwo.com\/conversion-rate-optimization\/\">convers\u00f5es<\/a>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Resultados de pesquisas org\u00e2nicas<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">A CTR dos resultados de pesquisas org\u00e2nicas depende de m\u00faltiplos fatores, como a posi\u00e7\u00e3o do resultado na p\u00e1gina do mecanismo de busca, a qualidade e a relev\u00e2ncia do t\u00edtulo e da meta descri\u00e7\u00e3o, a inten\u00e7\u00e3o de pesquisa do usu\u00e1rio e a concorr\u00eancia em uma determinada palavra-chave.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como m\u00e9trica, a CTR indica a relev\u00e2ncia de um an\u00fancio para os usu\u00e1rios. Se a CTR for:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Alta <\/strong>\u2013 os usu\u00e1rios acham que o an\u00fancio \u00e9 altamente relevante.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Baixa <\/strong>\u2013 os usu\u00e1rios consideram o an\u00fancio menos relevante.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">No entanto, \u00e9 importante lembrar que uma CTR alta nem sempre \u00e9 boa para suas campanhas pagas. Ter uma taxa de cliques elevada para uma palavra-chave irrelevante para o seu neg\u00f3cio pode ser prejudicial. Isso porque voc\u00ea paga por cada clique dos usu\u00e1rios. Logo, pagar por cliques irrelevantes significa que voc\u00ea est\u00e1 apenas gastando dinheiro sem gerar convers\u00f5es. Uma boa CTR deve ser atingida em palavras-chave relevantes e acess\u00edveis para gerar mais cliques em seus an\u00fancios.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>F\u00f3rmula para calcular a CTR<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A CTR \u00e9 calculada como a porcentagem de visitantes que visualizam um an\u00fancio (impress\u00f5es) e depois clicam de fato nele (cliques). A f\u00f3rmula para calcular a CTR \u00e9:<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"513\" data-id=\"921\" src=\"https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png\" alt=\"CTR Formula\" class=\"wp-image-921\" srcset=\"https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png?tr=w-1600 1600w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png?tr=w-1366 1366w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png?tr=w-1024 1024w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png?tr=w-768 768w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png?tr=w-640 640w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png?tr=w-375 375w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/figure>\n<figcaption class=\"blocks-gallery-caption wp-element-caption\"><span id=\"docs-internal-guid-c48f4d08-7fff-91c3-f2c0-d6f06e84cf77\"><span style=\"font-size: 10pt;font-family: Montserrat, sans-serif;vertical-align: baseline\">Fonte da imagem: <\/span><a href=\"https:\/\/snov.io\/glossary\/click-through-rate-ctr\/\" target=\"_blank\" rel=\"noreferrer noopener\"><span style=\"font-size: 10pt;font-family: Montserrat, sans-serif;vertical-align: baseline\">Snov<\/span><span style=\"font-size: 10pt;font-family: Montserrat, sans-serif;font-style: italic;vertical-align: baseline\">io<\/span><\/a><\/span><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Imagine que voc\u00ea queira monitorar a CTR de uma campanha paga nas redes sociais que oferece um teste gr\u00e1tis para os visitantes. O an\u00fancio foi exibido para 500 pessoas, mas apenas 40 delas clicaram no bot\u00e3o. Voc\u00ea pode calcular a taxa de cliques usando a f\u00f3rmula abaixo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CTR = (40 \/ 500) x 100% = 0.08 x 100% = 8%<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o importa o tipo de atividade de marketing que voc\u00ea esteja analisando, a f\u00f3rmula da taxa de cliques permanece a mesma.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Por que a CTR \u00e9 importante?<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A CTR \u00e9 uma m\u00e9trica importante que os anunciantes devem entender e monitorar pelos seguintes motivos:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Mensura\u00e7\u00e3o da capacidade de um an\u00fancio de atrair a aten\u00e7\u00e3o do usu\u00e1rio: ela informa o que funciona e o que n\u00e3o funciona junto aos clientes.<\/li>\n\n\n\n<li>Impacto direto no \u00edndice de qualidade: a pontua\u00e7\u00e3o \u00e9 medida por meio da CTR dos an\u00fancios, relev\u00e2ncia do an\u00fancio e experi\u00eancia da landing page para os usu\u00e1rios. Uma CTR mais alta levar\u00e1 a \u00edndices de qualidade mais altos.<\/li>\n\n\n\n<li>Classifica\u00e7\u00e3o do an\u00fancio: uma pontua\u00e7\u00e3o de alta qualidade faz com que o Google cobre menos por clique no an\u00fancio e coloque o conte\u00fado em uma posi\u00e7\u00e3o mais alta.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Qual \u00e9 uma boa CTR?<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Muitos anunciantes e profissionais de marketing podem se perguntar: qual \u00e9 uma boa CTR? A resposta \u00e9: depende. A CTR tem rela\u00e7\u00e3o com:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tipo de setor<\/li>\n\n\n\n<li>Conjunto de palavras-chave&nbsp;<\/li>\n\n\n\n<li>Diferentes campanhas individuais em uma conta PPC<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Abaixo est\u00e3o as refer\u00eancias para CTR no Google Ads de alguns setores comuns:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1104\" height=\"679\" src=\"https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2023\/05\/image.png\" alt=\"Image\" class=\"wp-image-1850\" srcset=\"https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2023\/05\/image.png 1104w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2023\/05\/image.png?tr=w-1024 1024w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2023\/05\/image.png?tr=w-768 768w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2023\/05\/image.png?tr=w-640 640w, https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2023\/05\/image.png?tr=w-375 375w\" sizes=\"(max-width: 1104px) 100vw, 1104px\" \/><figcaption class=\"wp-element-caption\">Fonte da imagem: <a href=\"https:\/\/www.wordstream.com\/click-through-rate\" target=\"_blank\" rel=\"noreferrer noopener\">WordStream<\/a><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Taxa de cliques e taxa de convers\u00e3o<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ter uma CTR alta indica que muitos usu\u00e1rios est\u00e3o clicando nos an\u00fancios, mas n\u00e3o informa o n\u00famero total de convers\u00f5es. Em termos simples, um an\u00fancio pode ter uma CTR alta com uma taxa de convers\u00e3o muito baixa, resultando em um alto <a href=\"https:\/\/www.techopedia.com\/definition\/23316\/cost-per-conversion-cpc#:~:text=Cost%20per%20conversion%20is%20a,which%20conversions%20are%20also%20tracked.\" target=\"_blank\" rel=\"noreferrer noopener\">custo por convers\u00e3o<\/a> para o anunciante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A <a href=\"https:\/\/vwo.com\/conversion-rate-optimization\/conversion-rate-optimisation-tips\/\">taxa de convers\u00e3o<\/a> \u00e9 a m\u00e9trica que mede a porcentagem de cliques que resultam em vendas reais. Portanto, trata-se de uma m\u00e9trica essencial para monitorar o sucesso de uma campanha. Para obter mais informa\u00e7\u00f5es sobre esse tema, leia este <a href=\"https:\/\/vwo.com\/blog\/conversion-rate-and-click-through-rate-difference\/\">artigo<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Fatores que afetam a CTR<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Alguns fatores que podem afetar a taxa de cliques s\u00e3o:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Relev\u00e2ncia do conte\u00fado: o conte\u00fado de qualquer an\u00fancio, e-mail ou campanha deve ter uma mensagem semelhante \u00e0 da landing page. Isso n\u00e3o \u00e9 importante apenas para a CTR, mas tamb\u00e9m para a <a href=\"https:\/\/vwo.com\/glossary\/br\/taxa-de-rejeicao\/\">taxa de rejei\u00e7\u00e3o<\/a> do site e, consequentemente, para as convers\u00f5es.&nbsp;<\/li>\n\n\n\n<li>Classifica\u00e7\u00e3o do an\u00fancio: a CTR do PPC tamb\u00e9m \u00e9 afetada pelo posicionamento do an\u00fancio na p\u00e1gina. A classifica\u00e7\u00e3o do an\u00fancio depende do \u00edndice de qualidade, da relev\u00e2ncia e do or\u00e7amento de <a href=\"https:\/\/vwo.com\/glossary\/cost-per-click\/\">custo por clique (CPC)<\/a>.<\/li>\n\n\n\n<li>Outros fatores, como imagens, palavras-chave, texto de CTA e posicionamento do an\u00fancio.<\/li>\n\n\n\n<li>Concorr\u00eancia no setor.<\/li>\n\n\n\n<li>P\u00fablico e tipo de segmenta\u00e7\u00e3o.<\/li>\n\n\n\n<li>URL de exibi\u00e7\u00e3o.<\/li>\n\n\n\n<li>Tipos de ofertas nas campanhas.<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Dicas para melhorar a CTR<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">N\u00e3o existe um n\u00famero definido que indique uma boa CTR. No entanto, diversos fatores influenciam a taxa de cliques. Para melhorar seus n\u00fameros e atingir uma CTR alta, considere as t\u00e9cnicas a seguir:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Compreenda o p\u00fablico-alvo: saber mais sobre o p\u00fablico-alvo resulta na cria\u00e7\u00e3o de an\u00fancios mais direcionados. Use ferramentas como a <a href=\"https:\/\/vwo.com\/br\/insights\/\">VWO Insights<\/a> para descobrir insights significativos sobre o comportamento dos visitantes no seu site.&nbsp;<\/li>\n\n\n\n<li>Realize pesquisas de palavras-chave: antes de criar qualquer an\u00fancio PPC, fa\u00e7a uma pesquisa para saber quais s\u00e3o as palavras-chave certas para segmentar. Isso economiza tempo e dinheiro, al\u00e9m de ajudar a determinar o potencial de cliques.<\/li>\n\n\n\n<li>Insira CTAs: incentive a a\u00e7\u00e3o dos visitantes com <a href=\"https:\/\/vwo.com\/glossary\/br\/call-to-action-cta\/\">CTAs<\/a> relevantes, que apresentem links para uma landing page correspondente ao texto do an\u00fancio.<\/li>\n\n\n\n<li>Use s\u00edmbolos: adicionar caracteres especiais e s\u00edmbolos que chamem a aten\u00e7\u00e3o do usu\u00e1rio faz com que o an\u00fancio se destaque.<\/li>\n\n\n\n<li>Insira imagens: imagens e outros elementos visuais podem aumentar as taxas de cliques. Considere a possibilidade de adicionar mais elementos visuais relevantes ou associados \u00e0 sua marca para aumentar o apelo do texto.<\/li>\n\n\n\n<li>Use extens\u00f5es de an\u00fancios: as extens\u00f5es de an\u00fancios, como avalia\u00e7\u00f5es, links de sites, localiza\u00e7\u00e3o, entre outras, ocupam mais espa\u00e7o na SERP e, consequentemente, chamam a aten\u00e7\u00e3o do visitante.<\/li>\n\n\n\n<li>Otimize para dispositivos m\u00f3veis: a <a href=\"https:\/\/vwo.com\/br\/testing\/mobile-app\/\">otimiza\u00e7\u00e3o para dispositivos m\u00f3veis<\/a> \u00e9 fundamental, pois garante que os usu\u00e1rios consigam navegar pelas suas p\u00e1ginas e visualizar seu conte\u00fado com facilidade em telas menores. Essa medida aumenta o engajamento e a CTR, evitando que os usu\u00e1rios percam o interesse no seu produto devido a uma experi\u00eancia ruim nos dispositivos m\u00f3veis.<\/li>\n\n\n\n<li><a href=\"https:\/\/vwo.com\/ab-testing\/\">Realize testes A\/B<\/a>: depois de considerar todos os fatores que est\u00e3o resultando em uma CTR baixa, o caminho a seguir \u00e9 testar cada etapa da jornada do usu\u00e1rio.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Conhe\u00e7a uma hist\u00f3ria de sucesso que prova como os testes A\/B podem aumentar a taxa de cliques das empresas.<br>Com sede na Carolina do Norte, nos EUA, a ArchiveSocial \u00e9 uma solu\u00e7\u00e3o de arquivamento de redes sociais baseada em SaaS que ajuda as organiza\u00e7\u00f5es a cumprir os requisitos legais e evitar processos judiciais. Um de seus objetivos era <a href=\"https:\/\/vwo.com\/conversion-rate-optimization\/conversion-rate-optimisation-tips\/\">aumentar as convers\u00f5es<\/a> do formul\u00e1rio do banner exibido na p\u00e1gina inicial de seu site. Com a ajuda da VWO, a empresa descobriu que o campo de endere\u00e7o de e-mail era exibido na parte inferior da p\u00e1gina sem nenhuma diferencia\u00e7\u00e3o do restante do conte\u00fado. Foi executado um teste em que o CTA foi movido para o lado direito da primeira dobra da p\u00e1gina. A varia\u00e7\u00e3o superou o desempenho da vers\u00e3o de controle e aumentou a taxa de cliques naquele campo do formul\u00e1rio em 101,68%. Para conhecer os outros testes que foram realizados, leia o estudo de caso completo <a href=\"https:\/\/vwo.com\/success-stories\/archivesocial\/\">aqui<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><strong>Algumas conclus\u00f5es importantes<\/strong><\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Diversos fatores afetam a probabilidade de algu\u00e9m clicar em um conte\u00fado ou an\u00fancio, impactando diretamente a CTR. Ainda assim, trata-se de um indicador \u00fatil que n\u00e3o deve ser usado apenas como m\u00e9trica de desempenho. A taxa de cliques pode ser combinada com as m\u00e9tricas abaixo para fornecer uma avalia\u00e7\u00e3o de desempenho aprimorada de qualquer campanha:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Levar a campanha ao p\u00fablico-alvo (impress\u00f5es)<\/li>\n\n\n\n<li>Manter os visitantes em uma p\u00e1gina depois do clique (taxa de rejei\u00e7\u00e3o)<\/li>\n\n\n\n<li>Incentivar os visitantes a realizarem a a\u00e7\u00e3o desejada (<a href=\"https:\/\/vwo.com\/glossary\/conversion-rate\/\">taxa de convers\u00e3o<\/a>)<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Goals | Setting up Goals - Tracks page visits on, Tracks clicks on links, Track form submits to Goal\" width=\"690\" height=\"388\" src=\"https:\/\/www.youtube.com\/embed\/qvP0-CMGY7Y?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Est\u00e1 se perguntando se \u00e9 poss\u00edvel medir mais de uma m\u00e9trica ou meta com a sua campanha de testes A\/B? O VWO Testing permite configurar metas ilimitadas em todos os planos. Isso significa que voc\u00ea consegue monitorar m\u00faltiplas metas e testar a efic\u00e1cia de seus testes A\/B por diferentes \u00e2ngulos. <a href=\"#free-trial\">Fa\u00e7a um teste gr\u00e1tis<\/a> e explore outras funcionalidades incr\u00edveis da nossa plataforma.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Perguntas frequentes sobre a taxa de cliques<\/strong><\/h2>\n\n\n\n<div class=\"schema-faq wp-block-yoast-faq-block\"><div class=\"schema-faq-section\" id=\"faq-question-1685012550708\"><strong class=\"schema-faq-question\"><strong><strong>Como calcular a CTR no Excel?<\/strong><\/strong><\/strong> <p class=\"schema-faq-answer\"><br \/>A f\u00f3rmula para calcular a CTR \u00e9 sempre a mesma, inclusive no Excel: n\u00famero total de cliques dividido pelo n\u00famero total de impress\u00f5es multiplicado por 100%.<br \/>Na multiplica\u00e7\u00e3o, use o asterisco (*) em vez do s\u00edmbolo \u201cx\u201d para calcular a CTR por esse m\u00e9todo.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1685012571634\"><strong class=\"schema-faq-question\"><br \/><strong>Qual \u00e9 uma boa CTR para marketing digital?<\/strong><\/strong> <p class=\"schema-faq-answer\"><br \/>De acordo com um <a href=\"https:\/\/www.smartinsights.com\/internet-advertising\/internet-advertising-analytics\/display-advertising-clickthrough-rates\/\" target=\"_blank\" rel=\"noreferrer noopener\">relat\u00f3rio<\/a> da Smart Insights, a CTR de pesquisas pagas \u00e9 de, em m\u00e9dia, 1,58%, enquanto a CTR dos an\u00fancios pagos em redes sociais \u00e9 de 1,36% e a dos an\u00fancios gr\u00e1ficos \u00e9 de 0,49%. Por outro lado, a <a href=\"https:\/\/mailchimp.com\/resources\/email-marketing-benchmarks\/\" target=\"_blank\" rel=\"noreferrer noopener\">CTR m\u00e9dia<\/a> para newsletters recebidas por e-mail \u00e9 de aproximadamente 3%. Mas \u00e9 preciso lembrar que uma boa taxa de cliques depende do tipo de setor em que voc\u00ea opera. Consulte o gr\u00e1fico exibido mais acima para saber qual \u00e9 uma boa CTR para o seu setor. Embora a CTR possa ser diferente para cada atividade de marketing e setor, sua f\u00f3rmula \u00e9 sempre a mesma.<\/p> <\/div> <div class=\"schema-faq-section\" id=\"faq-question-1685012603794\"><strong class=\"schema-faq-question\"><br \/><strong>Como encontro a taxa de cliques no Google Analytics?<\/strong><\/strong> <p class=\"schema-faq-answer\"><br \/>Voc\u00ea pode rastrear a CTR de seus an\u00fancios facilmente vinculando o Google Ads \u00e0 sua conta do Google Analytics. Dessa forma, \u00e9 poss\u00edvel visualizar o desempenho do an\u00fancio em termos de CTR, taxa de convers\u00e3o e at\u00e9 taxa de rejei\u00e7\u00e3o de forma mais abrangente no Google Analytics. Veja mais informa\u00e7\u00f5es <a href=\"https:\/\/support.google.com\/analytics\/answer\/1033961?hl=en#zippy=%2Cin-this-article\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a>.<\/p> <\/div> <\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A taxa de cliques (CTR) \u00e9 uma m\u00e9trica de marketing digital usada para medir o desempenho de um an\u00fancio. Ela indica o n\u00famero de cliques recebidos na campanha em rela\u00e7\u00e3o ao n\u00famero de visualiza\u00e7\u00f5es (impress\u00f5es).<\/p>\n","protected":false},"author":565,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-4544","post","type-post","status-publish","format-standard","hentry","category-uncategorized-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taxa de Cliques | VWO<\/title>\n<meta name=\"description\" content=\"A taxa de cliques (CTR) \u00e9 uma m\u00e9trica usada para medir o desempenho do an\u00fancio. Ela indica a porcentagem de cliques em rela\u00e7\u00e3o ao n\u00famero de impress\u00f5es.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taxa de Cliques | VWO\" \/>\n<meta property=\"og:description\" content=\"A taxa de cliques (CTR) \u00e9 uma m\u00e9trica usada para medir o desempenho do an\u00fancio. Ela indica a porcentagem de cliques em rela\u00e7\u00e3o ao n\u00famero de impress\u00f5es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/\" \/>\n<meta property=\"og:site_name\" content=\"VWO Glossary\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-02T07:01:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-02T15:37:08+00:00\" \/>\n<meta name=\"author\" content=\"avnishsharamav\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/\"},\"author\":{\"name\":\"avnishsharamav\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/#\\\/schema\\\/person\\\/620cb97e975598f02bdaf7e87d218044\"},\"headline\":\"Taxa de cliques (CTR)\",\"datePublished\":\"2022-03-02T07:01:01+00:00\",\"dateModified\":\"2025-12-02T15:37:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/\"},\"wordCount\":2030,\"image\":{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/static.wingify.com\\\/gcp\\\/uploads\\\/sites\\\/18\\\/2022\\\/06\\\/CTR-formula.png\",\"articleSection\":[\"Uncategorized @br\"],\"inLanguage\":\"br\"},{\"@type\":[\"WebPage\",\"FAQPage\"],\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/\",\"url\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/\",\"name\":\"Taxa de Cliques | VWO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/static.wingify.com\\\/gcp\\\/uploads\\\/sites\\\/18\\\/2022\\\/06\\\/CTR-formula.png\",\"datePublished\":\"2022-03-02T07:01:01+00:00\",\"dateModified\":\"2025-12-02T15:37:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/#\\\/schema\\\/person\\\/620cb97e975598f02bdaf7e87d218044\"},\"description\":\"A taxa de cliques (CTR) \u00e9 uma m\u00e9trica usada para medir o desempenho do an\u00fancio. Ela indica a porcentagem de cliques em rela\u00e7\u00e3o ao n\u00famero de impress\u00f5es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#breadcrumb\"},\"mainEntity\":[{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012550708\"},{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012571634\"},{\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012603794\"}],\"inLanguage\":\"br\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"br\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/static.wingify.com\\\/gcp\\\/uploads\\\/sites\\\/18\\\/2022\\\/06\\\/CTR-formula.png\",\"contentUrl\":\"https:\\\/\\\/static.wingify.com\\\/gcp\\\/uploads\\\/sites\\\/18\\\/2022\\\/06\\\/CTR-formula.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taxa de cliques (CTR)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/#website\",\"url\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/\",\"name\":\"VWO Glossary\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"br\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/#\\\/schema\\\/person\\\/620cb97e975598f02bdaf7e87d218044\",\"name\":\"avnishsharamav\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"br\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22365e2b149031ebe6765b34c2867074d90d098eaef4c785a0639612951281b1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22365e2b149031ebe6765b34c2867074d90d098eaef4c785a0639612951281b1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/22365e2b149031ebe6765b34c2867074d90d098eaef4c785a0639612951281b1?s=96&d=mm&r=g\",\"caption\":\"avnishsharamav\"}},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012550708\",\"position\":1,\"url\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012550708\",\"name\":\"Como calcular a CTR no Excel?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br \\\/>A f\u00f3rmula para calcular a CTR \u00e9 sempre a mesma, inclusive no Excel: n\u00famero total de cliques dividido pelo n\u00famero total de impress\u00f5es multiplicado por 100%.<br \\\/>Na multiplica\u00e7\u00e3o, use o asterisco (*) em vez do s\u00edmbolo \u201cx\u201d para calcular a CTR por esse m\u00e9todo.\",\"inLanguage\":\"br\"},\"inLanguage\":\"br\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012571634\",\"position\":2,\"url\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012571634\",\"name\":\"Qual \u00e9 uma boa CTR para marketing digital?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br \\\/>De acordo com um <a href=\\\"https:\\\/\\\/www.smartinsights.com\\\/internet-advertising\\\/internet-advertising-analytics\\\/display-advertising-clickthrough-rates\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">relat\u00f3rio<\\\/a> da Smart Insights, a CTR de pesquisas pagas \u00e9 de, em m\u00e9dia, 1,58%, enquanto a CTR dos an\u00fancios pagos em redes sociais \u00e9 de 1,36% e a dos an\u00fancios gr\u00e1ficos \u00e9 de 0,49%. Por outro lado, a <a href=\\\"https:\\\/\\\/mailchimp.com\\\/resources\\\/email-marketing-benchmarks\\\/\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">CTR m\u00e9dia<\\\/a> para newsletters recebidas por e-mail \u00e9 de aproximadamente 3%. Mas \u00e9 preciso lembrar que uma boa taxa de cliques depende do tipo de setor em que voc\u00ea opera. Consulte o gr\u00e1fico exibido mais acima para saber qual \u00e9 uma boa CTR para o seu setor. Embora a CTR possa ser diferente para cada atividade de marketing e setor, sua f\u00f3rmula \u00e9 sempre a mesma.\",\"inLanguage\":\"br\"},\"inLanguage\":\"br\"},{\"@type\":\"Question\",\"@id\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012603794\",\"position\":3,\"url\":\"https:\\\/\\\/vwo.com\\\/glossary\\\/br\\\/taxa-de-cliques\\\/#faq-question-1685012603794\",\"name\":\"Como encontro a taxa de cliques no Google Analytics?\",\"answerCount\":1,\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br \\\/>Voc\u00ea pode rastrear a CTR de seus an\u00fancios facilmente vinculando o Google Ads \u00e0 sua conta do Google Analytics. Dessa forma, \u00e9 poss\u00edvel visualizar o desempenho do an\u00fancio em termos de CTR, taxa de convers\u00e3o e at\u00e9 taxa de rejei\u00e7\u00e3o de forma mais abrangente no Google Analytics. Veja mais informa\u00e7\u00f5es <a href=\\\"https:\\\/\\\/support.google.com\\\/analytics\\\/answer\\\/1033961?hl=en#zippy=%2Cin-this-article\\\" target=\\\"_blank\\\" rel=\\\"noreferrer noopener\\\">aqui<\\\/a>.\",\"inLanguage\":\"br\"},\"inLanguage\":\"br\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taxa de Cliques | VWO","description":"A taxa de cliques (CTR) \u00e9 uma m\u00e9trica usada para medir o desempenho do an\u00fancio. Ela indica a porcentagem de cliques em rela\u00e7\u00e3o ao n\u00famero de impress\u00f5es.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/","og_locale":"en_US","og_type":"article","og_title":"Taxa de Cliques | VWO","og_description":"A taxa de cliques (CTR) \u00e9 uma m\u00e9trica usada para medir o desempenho do an\u00fancio. Ela indica a porcentagem de cliques em rela\u00e7\u00e3o ao n\u00famero de impress\u00f5es.","og_url":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/","og_site_name":"VWO Glossary","article_published_time":"2022-03-02T07:01:01+00:00","article_modified_time":"2025-12-02T15:37:08+00:00","author":"avnishsharamav","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#article","isPartOf":{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/"},"author":{"name":"avnishsharamav","@id":"https:\/\/vwo.com\/glossary\/br\/#\/schema\/person\/620cb97e975598f02bdaf7e87d218044"},"headline":"Taxa de cliques (CTR)","datePublished":"2022-03-02T07:01:01+00:00","dateModified":"2025-12-02T15:37:08+00:00","mainEntityOfPage":{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/"},"wordCount":2030,"image":{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#primaryimage"},"thumbnailUrl":"https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png","articleSection":["Uncategorized @br"],"inLanguage":"br"},{"@type":["WebPage","FAQPage"],"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/","url":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/","name":"Taxa de Cliques | VWO","isPartOf":{"@id":"https:\/\/vwo.com\/glossary\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#primaryimage"},"image":{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#primaryimage"},"thumbnailUrl":"https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png","datePublished":"2022-03-02T07:01:01+00:00","dateModified":"2025-12-02T15:37:08+00:00","author":{"@id":"https:\/\/vwo.com\/glossary\/br\/#\/schema\/person\/620cb97e975598f02bdaf7e87d218044"},"description":"A taxa de cliques (CTR) \u00e9 uma m\u00e9trica usada para medir o desempenho do an\u00fancio. Ela indica a porcentagem de cliques em rela\u00e7\u00e3o ao n\u00famero de impress\u00f5es.","breadcrumb":{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#breadcrumb"},"mainEntity":[{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012550708"},{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012571634"},{"@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012603794"}],"inLanguage":"br","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/"]}]},{"@type":"ImageObject","inLanguage":"br","@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#primaryimage","url":"https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png","contentUrl":"https:\/\/static.wingify.com\/gcp\/uploads\/sites\/18\/2022\/06\/CTR-formula.png"},{"@type":"BreadcrumbList","@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/vwo.com\/glossary\/br\/"},{"@type":"ListItem","position":2,"name":"Taxa de cliques (CTR)"}]},{"@type":"WebSite","@id":"https:\/\/vwo.com\/glossary\/br\/#website","url":"https:\/\/vwo.com\/glossary\/br\/","name":"VWO Glossary","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/vwo.com\/glossary\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"br"},{"@type":"Person","@id":"https:\/\/vwo.com\/glossary\/br\/#\/schema\/person\/620cb97e975598f02bdaf7e87d218044","name":"avnishsharamav","image":{"@type":"ImageObject","inLanguage":"br","@id":"https:\/\/secure.gravatar.com\/avatar\/22365e2b149031ebe6765b34c2867074d90d098eaef4c785a0639612951281b1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/22365e2b149031ebe6765b34c2867074d90d098eaef4c785a0639612951281b1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22365e2b149031ebe6765b34c2867074d90d098eaef4c785a0639612951281b1?s=96&d=mm&r=g","caption":"avnishsharamav"}},{"@type":"Question","@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012550708","position":1,"url":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012550708","name":"Como calcular a CTR no Excel?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"<br \/>A f\u00f3rmula para calcular a CTR \u00e9 sempre a mesma, inclusive no Excel: n\u00famero total de cliques dividido pelo n\u00famero total de impress\u00f5es multiplicado por 100%.<br \/>Na multiplica\u00e7\u00e3o, use o asterisco (*) em vez do s\u00edmbolo \u201cx\u201d para calcular a CTR por esse m\u00e9todo.","inLanguage":"br"},"inLanguage":"br"},{"@type":"Question","@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012571634","position":2,"url":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012571634","name":"Qual \u00e9 uma boa CTR para marketing digital?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"<br \/>De acordo com um <a href=\"https:\/\/www.smartinsights.com\/internet-advertising\/internet-advertising-analytics\/display-advertising-clickthrough-rates\/\" target=\"_blank\" rel=\"noreferrer noopener\">relat\u00f3rio<\/a> da Smart Insights, a CTR de pesquisas pagas \u00e9 de, em m\u00e9dia, 1,58%, enquanto a CTR dos an\u00fancios pagos em redes sociais \u00e9 de 1,36% e a dos an\u00fancios gr\u00e1ficos \u00e9 de 0,49%. Por outro lado, a <a href=\"https:\/\/mailchimp.com\/resources\/email-marketing-benchmarks\/\" target=\"_blank\" rel=\"noreferrer noopener\">CTR m\u00e9dia<\/a> para newsletters recebidas por e-mail \u00e9 de aproximadamente 3%. Mas \u00e9 preciso lembrar que uma boa taxa de cliques depende do tipo de setor em que voc\u00ea opera. Consulte o gr\u00e1fico exibido mais acima para saber qual \u00e9 uma boa CTR para o seu setor. Embora a CTR possa ser diferente para cada atividade de marketing e setor, sua f\u00f3rmula \u00e9 sempre a mesma.","inLanguage":"br"},"inLanguage":"br"},{"@type":"Question","@id":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012603794","position":3,"url":"https:\/\/vwo.com\/glossary\/br\/taxa-de-cliques\/#faq-question-1685012603794","name":"Como encontro a taxa de cliques no Google Analytics?","answerCount":1,"acceptedAnswer":{"@type":"Answer","text":"<br \/>Voc\u00ea pode rastrear a CTR de seus an\u00fancios facilmente vinculando o Google Ads \u00e0 sua conta do Google Analytics. Dessa forma, \u00e9 poss\u00edvel visualizar o desempenho do an\u00fancio em termos de CTR, taxa de convers\u00e3o e at\u00e9 taxa de rejei\u00e7\u00e3o de forma mais abrangente no Google Analytics. Veja mais informa\u00e7\u00f5es <a href=\"https:\/\/support.google.com\/analytics\/answer\/1033961?hl=en#zippy=%2Cin-this-article\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a>.","inLanguage":"br"},"inLanguage":"br"}]}},"_links":{"self":[{"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/posts\/4544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/users\/565"}],"replies":[{"embeddable":true,"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/comments?post=4544"}],"version-history":[{"count":6,"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/posts\/4544\/revisions"}],"predecessor-version":[{"id":6188,"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/posts\/4544\/revisions\/6188"}],"wp:attachment":[{"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/media?parent=4544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/categories?post=4544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vwo.com\/glossary\/br\/wp-json\/wp\/v2\/tags?post=4544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}